{"id":22435,"date":"2023-10-23T14:43:37","date_gmt":"2023-10-23T12:43:37","guid":{"rendered":"https:\/\/www.rimontgowineries.com\/blog\/?p=22435"},"modified":"2023-10-24T17:23:33","modified_gmt":"2023-10-24T15:23:33","slug":"claretes-2","status":"publish","type":"post","link":"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/","title":{"rendered":"Claretes"},"content":{"rendered":"<p>Se i vini rosati sono, in un certo senso, emarginati, i chiaretti sono la grande incognita. Tuttavia, di recente ho bevuto un chiaretto, Espantaburros, di C\u00e9sar Fern\u00e1ndez, un viticoltore di Pe\u00f1aranda de Duero, che mi ha portato a scrivere questo testo, non solo perch\u00e9 mi piaceva il vino ma anche perch\u00e9 difendeva un modo vituperato di farlo e che pu\u00f2 regalarci grandi momenti.<\/p>\n<p>L&#8217;Espantaburros, fatto con bobal, tempranillo e albillo mayor, \u00e8 un vino fresco, con struttura e ottima acidit\u00e0 -grazie soprattutto all&#8217;albillo- ma con note di frutta rossa delle variet\u00e0 rosse. Un vino senza complessit\u00e0, molto ben fatto, ideale per aperitivi ed estate. Le mie opinioni, ovviamente soggettive, possono essere pi\u00f9 o meno interessanti, ma quando si parla di questo tipo di vino bisogna partire dall&#8217;inizio e rispondere alla domanda d&#8217;obbligo: cos&#8217;\u00e8 un chiaretto?<\/p>\n<p>Il nome claret non appartiene a nessuna categoria ufficiale, ma \u00e8 il modo comune di chiamare un tipo di vino giovane, che si ottiene mescolando il mosto di uve bianche e rosse per la fermentazione congiunta, rispettando il processo di estrazione del mosto in ogni variet\u00e0. Come conseguenza della miscela, il colore del vino \u00e8 rosa tenue e le sue note aromatiche combinano quelle delle variet\u00e0 bianche con quelle rosse, principalmente Tempranillo. \u00c8 nelle zone di Castilla Le\u00f3n, come Cigales, Arlanza o Ribera del Duero, dove i chiaretti hanno una maggiore presenza.<\/p>\n<p>Da parte loro, i rosati, pi\u00f9 radicati in Rioja e Navarra, oltre a rispondere a una categoria ufficiale di vino, possono essere realizzati solo con variet\u00e0 rosse, ma senza la presenza di bucce, oppure aggiungendo anche variet\u00e0 bianche. La presenza di quest&#8217;ultimo \u00e8 minore, quindi i vini di solito hanno un po&#8217; pi\u00f9 di colore rispetto ai chiaretti. I rosati possono essere fatti in due modi: dissanguando, macerando l&#8217;uva rossa per poi estrarne il mosto privato delle parti solide, oppure pigiando, nel qual caso si trascina il colore della buccia. Inoltre i vini rosati, a causa della loro produzione pi\u00f9 complessa, hanno solitamente un invecchiamento pi\u00f9 o meno lungo, che li classifica in: giovane, crianza, reserva o gran reserva. Nel mondo dei vini rosati, \u00e8 obbligatorio nominare Vi\u00f1a Tondonia, prodotto da L\u00f3pez de Heredia, forse il miglior rosato del nostro paese.<\/p>\n<p>Le date estive sono il momento ottimale. Un barbecue, una paella, un riso al pesce o semplicemente una piscina o una spiaggia sono l&#8217;ideale per aprire e gustare un chiaretto o un giovane rosato, s\u00ec, sempre rispettando la filosofia del terroir. Provalo, non te ne pentirai.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli appuntamenti estivi sono il momento ottimale per bere i chiaretti, quelle grandi incognite. \u00c8 nelle zone di Castilla Le\u00f3n, come Cigales, Arlanza o Ribera del Duero, che i chiaretti sono pi\u00f9 presenti.<\/p>\n","protected":false},"author":2,"featured_media":22411,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3070,3100],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los Claretes | Rimontg\u00f3 Wineries<\/title>\n<meta name=\"description\" content=\"Se i vini rosati sono, in un certo senso, emarginati, i chiaretti sono le grandi incognite. Provatelo, non ve ne pentirete.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los Claretes | Rimontg\u00f3 Wineries\" \/>\n<meta property=\"og:description\" content=\"Se i vini rosati sono, in un certo senso, emarginati, i chiaretti sono le grandi incognite. Provatelo, non ve ne pentirete.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Rimontgo Wineries\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-23T12:43:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-24T15:23:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rimontgowineries.com\/blog\/wp-content\/uploads\/2023\/09\/1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juan Luis Vanrell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Luis Vanrell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/\"},\"author\":{\"name\":\"Juan Luis Vanrell\",\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/person\/9dc43a22f8b4b5cca821369523f3c455\"},\"headline\":\"Claretes\",\"datePublished\":\"2023-10-23T12:43:37+00:00\",\"dateModified\":\"2023-10-24T15:23:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/\"},\"wordCount\":415,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#organization\"},\"articleSection\":[\"Aziende vinicole\",\"Mondo del vino\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/\",\"url\":\"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/\",\"name\":\"Los Claretes | Rimontg\u00f3 Wineries\",\"isPartOf\":{\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#website\"},\"datePublished\":\"2023-10-23T12:43:37+00:00\",\"dateModified\":\"2023-10-24T15:23:33+00:00\",\"description\":\"Se i vini rosati sono, in un certo senso, emarginati, i chiaretti sono le grandi incognite. Provatelo, non ve ne pentirete.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.rimontgowineries.com\/blog\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Claretes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#website\",\"url\":\"https:\/\/www.rimontgowineries.com\/blog\/\",\"name\":\"Rimontgo Wineries\",\"description\":\"Rimontgo Wineries\",\"publisher\":{\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.rimontgowineries.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#organization\",\"name\":\"Rimontgo Wineries\",\"url\":\"https:\/\/www.rimontgowineries.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.rimontgowineries.com\/blog\/wp-content\/uploads\/2020\/03\/logo_bodegas_wineries_EN.svg\",\"contentUrl\":\"https:\/\/www.rimontgowineries.com\/blog\/wp-content\/uploads\/2020\/03\/logo_bodegas_wineries_EN.svg\",\"width\":134,\"height\":34,\"caption\":\"Rimontgo Wineries\"},\"image\":{\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/person\/9dc43a22f8b4b5cca821369523f3c455\",\"name\":\"Juan Luis Vanrell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ffaf84a9253780c50f123fc18a9c2266?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ffaf84a9253780c50f123fc18a9c2266?s=96&d=mm&r=g\",\"caption\":\"Juan Luis Vanrell\"},\"url\":\"https:\/\/www.rimontgowineries.com\/blog\/author\/juanluis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los Claretes | Rimontg\u00f3 Wineries","description":"Se i vini rosati sono, in un certo senso, emarginati, i chiaretti sono le grandi incognite. Provatelo, non ve ne pentirete.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/","og_locale":"es_ES","og_type":"article","og_title":"Los Claretes | Rimontg\u00f3 Wineries","og_description":"Se i vini rosati sono, in un certo senso, emarginati, i chiaretti sono le grandi incognite. Provatelo, non ve ne pentirete.","og_url":"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/","og_site_name":"Rimontgo Wineries","article_published_time":"2023-10-23T12:43:37+00:00","article_modified_time":"2023-10-24T15:23:33+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/www.rimontgowineries.com\/blog\/wp-content\/uploads\/2023\/09\/1.jpg","type":"image\/jpeg"}],"author":"Juan Luis Vanrell","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Juan Luis Vanrell","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/#article","isPartOf":{"@id":"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/"},"author":{"name":"Juan Luis Vanrell","@id":"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/person\/9dc43a22f8b4b5cca821369523f3c455"},"headline":"Claretes","datePublished":"2023-10-23T12:43:37+00:00","dateModified":"2023-10-24T15:23:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/"},"wordCount":415,"commentCount":0,"publisher":{"@id":"https:\/\/www.rimontgowineries.com\/blog\/#organization"},"articleSection":["Aziende vinicole","Mondo del vino"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/","url":"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/","name":"Los Claretes | Rimontg\u00f3 Wineries","isPartOf":{"@id":"https:\/\/www.rimontgowineries.com\/blog\/#website"},"datePublished":"2023-10-23T12:43:37+00:00","dateModified":"2023-10-24T15:23:33+00:00","description":"Se i vini rosati sono, in un certo senso, emarginati, i chiaretti sono le grandi incognite. Provatelo, non ve ne pentirete.","breadcrumb":{"@id":"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rimontgowineries.com\/blog\/it\/claretes-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rimontgowineries.com\/blog\/es\/"},{"@type":"ListItem","position":2,"name":"Claretes"}]},{"@type":"WebSite","@id":"https:\/\/www.rimontgowineries.com\/blog\/#website","url":"https:\/\/www.rimontgowineries.com\/blog\/","name":"Rimontgo Wineries","description":"Rimontgo Wineries","publisher":{"@id":"https:\/\/www.rimontgowineries.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rimontgowineries.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.rimontgowineries.com\/blog\/#organization","name":"Rimontgo Wineries","url":"https:\/\/www.rimontgowineries.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.rimontgowineries.com\/blog\/wp-content\/uploads\/2020\/03\/logo_bodegas_wineries_EN.svg","contentUrl":"https:\/\/www.rimontgowineries.com\/blog\/wp-content\/uploads\/2020\/03\/logo_bodegas_wineries_EN.svg","width":134,"height":34,"caption":"Rimontgo Wineries"},"image":{"@id":"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/person\/9dc43a22f8b4b5cca821369523f3c455","name":"Juan Luis Vanrell","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ffaf84a9253780c50f123fc18a9c2266?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ffaf84a9253780c50f123fc18a9c2266?s=96&d=mm&r=g","caption":"Juan Luis Vanrell"},"url":"https:\/\/www.rimontgowineries.com\/blog\/author\/juanluis\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/posts\/22435"}],"collection":[{"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/comments?post=22435"}],"version-history":[{"count":2,"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/posts\/22435\/revisions"}],"predecessor-version":[{"id":22458,"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/posts\/22435\/revisions\/22458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/media\/22411"}],"wp:attachment":[{"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/media?parent=22435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/categories?post=22435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/tags?post=22435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}