{"id":22487,"date":"2023-11-08T16:04:19","date_gmt":"2023-11-08T15:04:19","guid":{"rendered":"https:\/\/www.rimontgowineries.com\/blog\/?p=22487"},"modified":"2023-11-08T16:05:04","modified_gmt":"2023-11-08T15:05:04","slug":"absurde-trends-i-rioja-oder-ribera","status":"publish","type":"post","link":"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/","title":{"rendered":"Absurde Trends (I): RIOJA oder RIBERA?"},"content":{"rendered":"<p>Wie in jedem Lebensbereich gibt es auch in der Weinwelt viele absurde Themen. Vielleicht ist es einfach die schlechte Angewohnheit der Gesellschaft, die Meinungen der Mitmenschen zu hinterfragen, um die eigene durchzusetzen, obwohl ich es in diesem Fall auf einen Mangel an Perspektive und vor allem an Wissen zur\u00fcckf\u00fchre. Ich werde eine Reihe von Beispielen anf\u00fchren, in denen sich viele Menschen widerspiegeln k\u00f6nnen und mit denen sie vielleicht verstehen, was ich ausdr\u00fccken m\u00f6chte.<\/p>\n<p>In diesem Eintrag beginne ich mit einem der abgedroschensten Klischees: \u201eIch komme eher aus Rioja als aus Ribera\u201c oder umgekehrt. Eine Aussage wie diese ist bedeutungslos. Verallgemeinerungen sind immer unfair, abgesehen davon, dass sie eine sehr wichtige Vorstellung von Rioja- und Ribera del Duero-Weinen haben, was in der breiten \u00d6ffentlichkeit nicht \u00fcblich ist. Rioja hat zwei Arten der Weinherstellung, eine klassische und die andere moderne. Innerhalb jeder gibt es verschiedene Weing\u00fcter mit unterschiedlichen Besonderheiten und nicht unbedingt deswegen, einige sind besser als andere, nur anders und in beiden F\u00e4llen k\u00f6nnen sie au\u00dfergew\u00f6hnliche Weine produzieren. Dar\u00fcber hinaus k\u00f6nnen wir hinzuf\u00fcgen, dass es in Rioja drei Zonen und auch mehrere Sorten gibt, rot und wei\u00df. Dieselben Argumente gelten auch f\u00fcr Ribera del Duero, ohne zu vergessen, dass es Valladolid, Burgos und Soria umfasst.<\/p>\n<p>Bei alledem m\u00f6chte ich sagen, dass das Klischee \u201eIch bin mehr aus Rioja als aus Ribera\u201c oder umgekehrt viele Variablen impliziert, die die Aussage zu einem wirklich absurden Klischee machen. W\u00fcrden wir eine Blindverkostung von Rioja-Weinen im Vergleich zu anderen aus Ribera machen, w\u00fcrden die meisten, die eine solche Aussage machen, ernsthafte Probleme haben, sie zu unterscheiden, denn es gibt Rioja- und Ribera del Duero-Weine, die bei \u00e4hnlichen Herstellungsmethoden viele Punkte haben weit verbreitet, was logisch ist, da Tempranillo &#8211; in Ribera del Duero als feine Tinta oder Tinta del Pa\u00eds bezeichnet &#8211; die vorherrschende Rebsorte in beiden Weinregionen ist.<\/p>\n<p>Besonders verallgemeinernd f\u00e4llt es mir schwer zu sagen, ob ich Rioja- oder Ribera-Weine mehr mag. Es f\u00e4llt mir genauso schwer, mich eher klassischen Rioja-Weinen zuzuwenden als modernen, denn in beiden Produktionsformen stecken authentische Wunderwerke. Sind Sie nach dieser kurzen Analyse immer noch mehr aus Rioja als aus Ribera del Duero oder umgekehrt?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dieser Artikel analysiert die Gemeinsamkeiten und Unterschiede zwischen diesen beiden Weinregionen, stellt absurde Klischees in Frage und hebt die Geschmacksvielfalt hervor, die beide bieten. Sind Sie immer noch eher von Rioja oder Ribera del Duero, nachdem Sie die Wahrheit erfahren haben?<\/p>\n","protected":false},"author":2,"featured_media":22482,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3098],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entlarvung der Weinmythen \/ Rimontg\u00f3 Wineries<\/title>\n<meta name=\"description\" content=\"Entdecken Sie, warum die ewige Rivalit\u00e4t zwischen Weinliebhabern aus Rioja und Ribera del Duero bedeutungslos ist.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entlarvung der Weinmythen \/ Rimontg\u00f3 Wineries\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie, warum die ewige Rivalit\u00e4t zwischen Weinliebhabern aus Rioja und Ribera del Duero bedeutungslos ist.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/\" \/>\n<meta property=\"og:site_name\" content=\"Rimontgo Wineries\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-08T15:04:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-08T15:05:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rimontgowineries.com\/blog\/wp-content\/uploads\/2023\/11\/Topicos-absurdos.-Rioja-o-Ribera-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1530\" \/>\n\t<meta property=\"og:image:height\" content=\"1020\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juan Luis Vanrell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Luis Vanrell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/\"},\"author\":{\"name\":\"Juan Luis Vanrell\",\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/person\/9dc43a22f8b4b5cca821369523f3c455\"},\"headline\":\"Absurde Trends (I): RIOJA oder RIBERA?\",\"datePublished\":\"2023-11-08T15:04:19+00:00\",\"dateModified\":\"2023-11-08T15:05:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/\"},\"wordCount\":383,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#organization\"},\"articleSection\":[\"Weinwelt\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/\",\"url\":\"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/\",\"name\":\"Entlarvung der Weinmythen \/ Rimontg\u00f3 Wineries\",\"isPartOf\":{\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#website\"},\"datePublished\":\"2023-11-08T15:04:19+00:00\",\"dateModified\":\"2023-11-08T15:05:04+00:00\",\"description\":\"Entdecken Sie, warum die ewige Rivalit\u00e4t zwischen Weinliebhabern aus Rioja und Ribera del Duero bedeutungslos ist.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.rimontgowineries.com\/blog\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Absurde Trends (I): RIOJA oder RIBERA?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#website\",\"url\":\"https:\/\/www.rimontgowineries.com\/blog\/\",\"name\":\"Rimontgo Wineries\",\"description\":\"Rimontgo Wineries\",\"publisher\":{\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.rimontgowineries.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#organization\",\"name\":\"Rimontgo Wineries\",\"url\":\"https:\/\/www.rimontgowineries.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.rimontgowineries.com\/blog\/wp-content\/uploads\/2020\/03\/logo_bodegas_wineries_EN.svg\",\"contentUrl\":\"https:\/\/www.rimontgowineries.com\/blog\/wp-content\/uploads\/2020\/03\/logo_bodegas_wineries_EN.svg\",\"width\":134,\"height\":34,\"caption\":\"Rimontgo Wineries\"},\"image\":{\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/person\/9dc43a22f8b4b5cca821369523f3c455\",\"name\":\"Juan Luis Vanrell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ffaf84a9253780c50f123fc18a9c2266?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ffaf84a9253780c50f123fc18a9c2266?s=96&d=mm&r=g\",\"caption\":\"Juan Luis Vanrell\"},\"url\":\"https:\/\/www.rimontgowineries.com\/blog\/author\/juanluis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entlarvung der Weinmythen \/ Rimontg\u00f3 Wineries","description":"Entdecken Sie, warum die ewige Rivalit\u00e4t zwischen Weinliebhabern aus Rioja und Ribera del Duero bedeutungslos ist.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/","og_locale":"es_ES","og_type":"article","og_title":"Entlarvung der Weinmythen \/ Rimontg\u00f3 Wineries","og_description":"Entdecken Sie, warum die ewige Rivalit\u00e4t zwischen Weinliebhabern aus Rioja und Ribera del Duero bedeutungslos ist.","og_url":"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/","og_site_name":"Rimontgo Wineries","article_published_time":"2023-11-08T15:04:19+00:00","article_modified_time":"2023-11-08T15:05:04+00:00","og_image":[{"width":1530,"height":1020,"url":"https:\/\/www.rimontgowineries.com\/blog\/wp-content\/uploads\/2023\/11\/Topicos-absurdos.-Rioja-o-Ribera-1.jpg","type":"image\/jpeg"}],"author":"Juan Luis Vanrell","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Juan Luis Vanrell","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/#article","isPartOf":{"@id":"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/"},"author":{"name":"Juan Luis Vanrell","@id":"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/person\/9dc43a22f8b4b5cca821369523f3c455"},"headline":"Absurde Trends (I): RIOJA oder RIBERA?","datePublished":"2023-11-08T15:04:19+00:00","dateModified":"2023-11-08T15:05:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/"},"wordCount":383,"commentCount":0,"publisher":{"@id":"https:\/\/www.rimontgowineries.com\/blog\/#organization"},"articleSection":["Weinwelt"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/","url":"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/","name":"Entlarvung der Weinmythen \/ Rimontg\u00f3 Wineries","isPartOf":{"@id":"https:\/\/www.rimontgowineries.com\/blog\/#website"},"datePublished":"2023-11-08T15:04:19+00:00","dateModified":"2023-11-08T15:05:04+00:00","description":"Entdecken Sie, warum die ewige Rivalit\u00e4t zwischen Weinliebhabern aus Rioja und Ribera del Duero bedeutungslos ist.","breadcrumb":{"@id":"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rimontgowineries.com\/blog\/de\/absurde-trends-i-rioja-oder-ribera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rimontgowineries.com\/blog\/es\/"},{"@type":"ListItem","position":2,"name":"Absurde Trends (I): RIOJA oder RIBERA?"}]},{"@type":"WebSite","@id":"https:\/\/www.rimontgowineries.com\/blog\/#website","url":"https:\/\/www.rimontgowineries.com\/blog\/","name":"Rimontgo Wineries","description":"Rimontgo Wineries","publisher":{"@id":"https:\/\/www.rimontgowineries.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rimontgowineries.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.rimontgowineries.com\/blog\/#organization","name":"Rimontgo Wineries","url":"https:\/\/www.rimontgowineries.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.rimontgowineries.com\/blog\/wp-content\/uploads\/2020\/03\/logo_bodegas_wineries_EN.svg","contentUrl":"https:\/\/www.rimontgowineries.com\/blog\/wp-content\/uploads\/2020\/03\/logo_bodegas_wineries_EN.svg","width":134,"height":34,"caption":"Rimontgo Wineries"},"image":{"@id":"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/person\/9dc43a22f8b4b5cca821369523f3c455","name":"Juan Luis Vanrell","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rimontgowineries.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ffaf84a9253780c50f123fc18a9c2266?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ffaf84a9253780c50f123fc18a9c2266?s=96&d=mm&r=g","caption":"Juan Luis Vanrell"},"url":"https:\/\/www.rimontgowineries.com\/blog\/author\/juanluis\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/posts\/22487"}],"collection":[{"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/comments?post=22487"}],"version-history":[{"count":2,"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/posts\/22487\/revisions"}],"predecessor-version":[{"id":22489,"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/posts\/22487\/revisions\/22489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/media\/22482"}],"wp:attachment":[{"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/media?parent=22487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/categories?post=22487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rimontgowineries.com\/blog\/wp-json\/wp\/v2\/tags?post=22487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}